{"id":5197,"date":"2023-11-20T10:45:08","date_gmt":"2023-11-20T09:45:08","guid":{"rendered":"https:\/\/www.spamotos.com\/?p=5197"},"modified":"2026-03-05T17:02:21","modified_gmt":"2026-03-05T16:02:21","slug":"why-ewc-2024-schedule-ticks-all-the-boxes","status":"publish","type":"post","link":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/","title":{"rendered":"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5197\" class=\"elementor elementor-5197 elementor-5187\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-501f238 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"501f238\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3a5570\" data-id=\"e3a5570\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d03770c elementor-widget elementor-widget-heading\" data-id=\"d03770c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Why EWC 2024 schedule ticks all the boxes ?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-013a4d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"013a4d0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5296bd4\" data-id=\"5296bd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20fa68e elementor-widget elementor-widget-heading\" data-id=\"20fa68e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pour le calendrier EWC 2024 coche-t-il toutes les cases ?\n\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3411be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3411be\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9300245\" data-id=\"9300245\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f242e1 elementor-widget elementor-widget-text-editor\" data-id=\"4f242e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><strong>The calendar for the 2024 FIM Endurance World Championship features \u201clegendary events at famous racetracks\u201d, while also being \u201caccessible and achievable in practical and financial terms\u201d.<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdd541e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bdd541e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0e9631\" data-id=\"a0e9631\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cd5b02 elementor-widget elementor-widget-text-editor\" data-id=\"0cd5b02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Consisting of four rounds from April to September \u2013 the 24 Heures Motos, the 8 Hours of Spa Motos, the 45th Coca-Cola Suzuka 8 Hours Endurance Race \u2013 the EWC calendar was announced last month and has been well received by the competing teams.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e936f7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e936f7c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-727733b\" data-id=\"727733b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e8afa0 elementor-widget elementor-widget-text-editor\" data-id=\"9e8afa0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<strong>Le calendrier du Championnat du Monde FIM d&#8217;Endurance 2024 pr\u00e9sente des &#8220;\u00e9v\u00e9nements l\u00e9gendaires sur des circuits c\u00e9l\u00e8bres&#8221;, tout en \u00e9tant &#8220;accessible et r\u00e9alisable en termes pratiques et financiers&#8221;.\n<\/strong>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1da409c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1da409c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bd9a4d\" data-id=\"2bd9a4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2ce11e elementor-widget elementor-widget-text-editor\" data-id=\"c2ce11e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Compos\u00e9 de quatre manches d&#8217;avril \u00e0 septembre &#8211; les 24 Heures Motos, les 8 Heures de Spa Motos, la 45e course Coca-Cola Suzuka 8 Heures Endurance et enfin le Bol d&#8217;Or &#8211; le calendrier EWC a \u00e9t\u00e9 annonc\u00e9 le mois dernier et a \u00e9t\u00e9 bien accueilli par les \u00e9quipes en lice.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e1e95ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1e95ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74098e2\" data-id=\"74098e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7f6646 elementor-widget elementor-widget-text-editor\" data-id=\"a7f6646\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Jean-Baptiste Ley, EWC Series\u2019 Director for promoter Warner Bros Discovery Sports, said:<\/strong> \u201c<i>We are delighted to present the calendar for the 2024 FIM Endurance World Championship when we will continue to count on legendary events at famous racetracks. Although expanding the calendar to include a fifth round remains a long-term target, it\u2019s vital that we deliver a schedule that is accessible and achievable in practical and financial terms. The 2024 calendar achieves both and we look forward to another action-packed season.&#8221;\u00a0<\/i><\/p><p><i>\u00a0<\/i><\/p><p><i>\u201cThere has been a change to the format of the Spa event, which will strengthen the championship and assist our riders and teams. And in another exciting and positive move for the new season, the Suzuka 8 Hours will form part of the FIM Endurance World Cup schedule although Superstock teams will count their best three scores across the year, meaning participation in this event is not mandatory.<\/i>\u201d<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e197085 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e197085\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6ad00d\" data-id=\"e6ad00d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b24a51 elementor-widget elementor-widget-text-editor\" data-id=\"8b24a51\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Jean-Baptiste Ley, directeur de la s\u00e9rie EWC pour le promoteur Warner Bros Discovery Sports, a d\u00e9clar\u00e9 :<\/strong>\u00a0<em>&#8220;Nous sommes ravis de pr\u00e9senter le calendrier du Championnat du Monde FIM d&#8217;Endurance 2024, lorsque nous continuerons \u00e0 compter sur des \u00e9v\u00e9nements l\u00e9gendaires sur des circuits c\u00e9l\u00e8bres. Bien que l&#8217;\u00e9largissement du calendrier pour inclure une cinqui\u00e8me manche reste un objectif \u00e0 long terme, il est essentiel que nous proposions un calendrier accessible et r\u00e9alisable en termes pratiques et financiers. Le calendrier 2024 remplit ces deux conditions et nous attendons avec impatience une nouvelle saison pleine d&#8217;action.<\/em><\/p><p><em>\u00a0<\/em><\/p><p><em>&#8220;Le format de l&#8217;\u00e9preuve de Spa a \u00e9t\u00e9 modifi\u00e9, ce qui renforcera le championnat et aidera nos pilotes et nos \u00e9quipes. Et dans une autre dynamique excitante et positive pour la nouvelle saison, les 8 Heures de Suzuka feront partie du calendrier de la Coupe du Monde d&#8217;Endurance FIM, bien que les \u00e9quipes Superstock compteront leurs trois meilleurs scores de l&#8217;ann\u00e9e, ce qui signifie que la participation \u00e0 cette \u00e9preuve n&#8217;est pas obligatoire.&#8221;<\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa709cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa709cd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-514009f\" data-id=\"514009f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e0c31e elementor-widget elementor-widget-text-editor\" data-id=\"5e0c31e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Paul King, FIM Circuit Racing Commission Director added:<\/strong> \u201cAn excellent event programme for 2024, responding to the needs of competitors, promotors and partner organisations to strengthen the FIM Endurance World Championship and FIM Endurance World Cup in the long term.<\/p><p>\u201cIt\u2019s good to see the opportunity for Superstock competitors to take part in the Suzuka event for the first time in 2024 \u2013 always a special event on the global motorcycle calendar. The FIM CCR and WBDS together have already agreed to count the best three scores from the four FIM Endurance World Cup rounds and to allow Superstock teams a fourth rider in the 24-hour events to enable and encourage participation.\u201d<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0800e64 elementor-widget elementor-widget-text-editor\" data-id=\"0800e64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Paul King, Directeur de la Commission des courses sur circuit de la FIM, a ajout\u00e9<\/strong> :<em>\u00a0&#8220;Un excellent programme de manifestations pour 2024, r\u00e9pondant aux besoins des concurrents, des promoteurs et des organisations partenaires pour renforcer le Championnat du Monde d&#8217;Endurance FIM et la Coupe du Monde d&#8217;Endurance FIM sur le long terme.<\/em><br \/><br \/><em>&#8220;Il est bon de voir l&#8217;opportunit\u00e9 pour les concurrents Superstock de participer \u00e0 la manifestation de Suzuka pour la premi\u00e8re fois en 2024 &#8211; toujours un \u00e9v\u00e9nement sp\u00e9cial dans le calendrier mondial de la moto. Le CCR FIM et le WBDS ont d\u00e9j\u00e0 convenu ensemble de compter les trois meilleurs scores des quatre manches de la Coupe du monde d&#8217;endurance FIM et d&#8217;autoriser les \u00e9quipes Superstock \u00e0 avoir un quatri\u00e8me pilote dans les \u00e9preuves de 24 heures afin de permettre et d&#8217;encourager la participation.&#8221;<\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8032b0c elementor-widget elementor-widget-image\" data-id=\"8032b0c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance-1024x1024.jpg 1024w, https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance-300x300.jpg 300w, https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance-150x150.jpg 150w, https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance-768x768.jpg 768w, https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance-1536x1536.jpg 1536w, https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dbd371 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1dbd371\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca71b2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca71b2b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3617bcd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3617bcd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ee992a2\" data-id=\"ee992a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b959a45 elementor-widget elementor-widget-text-editor\" data-id=\"b959a45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Rappel du calendrier de l&#8217;EWC 2024 :<\/strong><\/p><p><br \/><strong>Manche 1 :<\/strong> 24 Heures Motos (Le Mans, France) : 18-21 avril<br \/><strong>Manche 2 :<\/strong> 8 Heures de Spa Motos (Circuit de Spa-Francorchamps, Belgique) : 6-8 juin<br \/><strong>3\u00e8me manche : <\/strong>45\u00e8me Coca-Cola Suzuka 8 Hours Endurance Race (Japon) : 18-21 juillet<br \/><strong>4\u00e8me manche : <\/strong>Bol d&#8217;Or (Circuit Paul Ricard, France) : 12-15 septembre<\/p><p><br \/><i>Toutes les manches compteront pour le Championnat du Monde d&#8217;Endurance FIM et la Coupe du Monde d&#8217;Endurance FIM. Les \u00e9quipes de la Coupe du Monde d&#8217;Endurance FIM retiendront leurs trois meilleurs scores.<\/i><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ab9640\" data-id=\"6ab9640\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29032cc elementor-widget elementor-widget-text-editor\" data-id=\"29032cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<strong>EWC 2024 calendar refresher :\u00a0<\/strong>\n<br><br>\n<strong>\nRound 1:<\/strong>\u00a024 Heures Motos (Le Mans, France): 18-21 April\n<br><strong>Round 2:<\/strong>\u00a08 Hours of Spa Motos (Circuit de Spa-Francorchamps, Belgium): 6-8 June\n<br><strong>Round 3:\u00a0<\/strong>45th Coca-Cola Suzuka 8 Hours Endurance Race, Japan): 18-21 July\n<br><strong>Round 4:<\/strong>\u00a0Bol d\u2019Or (Circuit Paul Ricard, France): 12-15 September\n\n<em>\u00a0<\/em>\n\n<em><br><br>All the rounds will count for the FIM Endurance World Championship and FIM Endurance World Cup. FIM Endurance World Cup teams count their best three scores.<\/em>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3833a99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3833a99\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-feef45d\" data-id=\"feef45d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f60454 elementor-widget elementor-widget-spacer\" data-id=\"1f60454\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));-ms-flex-item-align:stretch;align-self:stretch;-ms-flex-negative:0;flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff3b583 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ff3b583\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.fimewc.fr\/news\/why-ewc-2024-schedule-ticks-all-the-boxes\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Acc\u00e8der au communiqu\u00e9 \/  Access the press release<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Why EWC 2024 schedule ticks all the boxes ? Pour le calendrier EWC 2024 coche-t-il toutes les cases ? The calendar for the 2024 FIM Endurance World Championship features \u201clegendary events at famous racetracks\u201d, while also being \u201caccessible and achievable in practical and financial terms\u201d. Consisting of four rounds from April to September \u2013 the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5185,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62,54],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b - 8h SPA Motos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b - 8h SPA Motos\" \/>\n<meta property=\"og:description\" content=\"Why EWC 2024 schedule ticks all the boxes ? Pour le calendrier EWC 2024 coche-t-il toutes les cases ? The calendar for the 2024 FIM Endurance World Championship features \u201clegendary events at famous racetracks\u201d, while also being \u201caccessible and achievable in practical and financial terms\u201d. Consisting of four rounds from April to September \u2013 the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/\" \/>\n<meta property=\"og:site_name\" content=\"8h SPA Motos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/24hspamotos\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-20T09:45:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T16:02:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@24hspamotos\" \/>\n<meta name=\"twitter:site\" content=\"@24hspamotos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/\"},\"author\":{\"name\":\"Administrateur\",\"@id\":\"https:\/\/www.spamotos.com\/en\/#\/schema\/person\/6c5133ba53ed7caade8af07521ce45ce\"},\"headline\":\"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b\",\"datePublished\":\"2023-11-20T09:45:08+00:00\",\"dateModified\":\"2026-03-05T16:02:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/\"},\"wordCount\":884,\"publisher\":{\"@id\":\"https:\/\/www.spamotos.com\/en\/#organization\"},\"articleSection\":[\"2024 Season\",\"EWC News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/\",\"url\":\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/\",\"name\":\"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b - 8h SPA Motos\",\"isPartOf\":{\"@id\":\"https:\/\/www.spamotos.com\/en\/#website\"},\"datePublished\":\"2023-11-20T09:45:08+00:00\",\"dateModified\":\"2026-03-05T16:02:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.spamotos.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.spamotos.com\/en\/#website\",\"url\":\"https:\/\/www.spamotos.com\/en\/\",\"name\":\"8h SPA Motos\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.spamotos.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.spamotos.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.spamotos.com\/en\/#organization\",\"name\":\"8h SPA Motos\",\"url\":\"https:\/\/www.spamotos.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.spamotos.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/11\/cropped-8Hours-Positif-test-2.png\",\"contentUrl\":\"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/11\/cropped-8Hours-Positif-test-2.png\",\"width\":443,\"height\":200,\"caption\":\"8h SPA Motos\"},\"image\":{\"@id\":\"https:\/\/www.spamotos.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/24hspamotos\",\"https:\/\/twitter.com\/24hspamotos\",\"https:\/\/www.instagram.com\/24hspamotos\",\"https:\/\/www.tiktok.com\/@24hspamotos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.spamotos.com\/en\/#\/schema\/person\/6c5133ba53ed7caade8af07521ce45ce\",\"name\":\"Administrateur\",\"sameAs\":[\"https:\/\/www.spamotos.com\/wp-cms\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b - 8h SPA Motos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/","og_locale":"en_US","og_type":"article","og_title":"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b - 8h SPA Motos","og_description":"Why EWC 2024 schedule ticks all the boxes ? Pour le calendrier EWC 2024 coche-t-il toutes les cases ? The calendar for the 2024 FIM Endurance World Championship features \u201clegendary events at famous racetracks\u201d, while also being \u201caccessible and achievable in practical and financial terms\u201d. Consisting of four rounds from April to September \u2013 the [&hellip;]","og_url":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/","og_site_name":"8h SPA Motos","article_publisher":"https:\/\/www.facebook.com\/24hspamotos","article_published_time":"2023-11-20T09:45:08+00:00","article_modified_time":"2026-03-05T16:02:21+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/12\/Calendrier-Endurance.jpg","type":"image\/jpeg"}],"author":"Administrateur","twitter_card":"summary_large_image","twitter_creator":"@24hspamotos","twitter_site":"@24hspamotos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/#article","isPartOf":{"@id":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/"},"author":{"name":"Administrateur","@id":"https:\/\/www.spamotos.com\/en\/#\/schema\/person\/6c5133ba53ed7caade8af07521ce45ce"},"headline":"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b","datePublished":"2023-11-20T09:45:08+00:00","dateModified":"2026-03-05T16:02:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/"},"wordCount":884,"publisher":{"@id":"https:\/\/www.spamotos.com\/en\/#organization"},"articleSection":["2024 Season","EWC News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/","url":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/","name":"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b - 8h SPA Motos","isPartOf":{"@id":"https:\/\/www.spamotos.com\/en\/#website"},"datePublished":"2023-11-20T09:45:08+00:00","dateModified":"2026-03-05T16:02:21+00:00","breadcrumb":{"@id":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.spamotos.com\/en\/why-ewc-2024-schedule-ticks-all-the-boxes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.spamotos.com\/en\/"},{"@type":"ListItem","position":2,"name":"WHY EWC 2024 SCHEDULE TICKS ALL THE BOXES ?\u200b"}]},{"@type":"WebSite","@id":"https:\/\/www.spamotos.com\/en\/#website","url":"https:\/\/www.spamotos.com\/en\/","name":"8h SPA Motos","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.spamotos.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.spamotos.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.spamotos.com\/en\/#organization","name":"8h SPA Motos","url":"https:\/\/www.spamotos.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.spamotos.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/11\/cropped-8Hours-Positif-test-2.png","contentUrl":"https:\/\/www.spamotos.com\/wp-content\/uploads\/2023\/11\/cropped-8Hours-Positif-test-2.png","width":443,"height":200,"caption":"8h SPA Motos"},"image":{"@id":"https:\/\/www.spamotos.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/24hspamotos","https:\/\/twitter.com\/24hspamotos","https:\/\/www.instagram.com\/24hspamotos","https:\/\/www.tiktok.com\/@24hspamotos"]},{"@type":"Person","@id":"https:\/\/www.spamotos.com\/en\/#\/schema\/person\/6c5133ba53ed7caade8af07521ce45ce","name":"Administrateur","sameAs":["https:\/\/www.spamotos.com\/wp-cms"]}]}},"_links":{"self":[{"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/posts\/5197"}],"collection":[{"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/comments?post=5197"}],"version-history":[{"count":8,"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/posts\/5197\/revisions"}],"predecessor-version":[{"id":11501,"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/posts\/5197\/revisions\/11501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/media\/5185"}],"wp:attachment":[{"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/media?parent=5197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/categories?post=5197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spamotos.com\/en\/wp-json\/wp\/v2\/tags?post=5197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}